{"id":141,"count":0,"description":"","link":"https:\/\/allsevillaguides.com\/it\/category\/tour-a-piedi\/","name":"Tour a piedi","slug":"tour-a-piedi","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tour a piedi archivos | All sevilla Guides<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/allsevillaguides.com\/it\/category\/tour-a-piedi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour a piedi archivos | All sevilla Guides\" \/>\n<meta property=\"og:url\" content=\"https:\/\/allsevillaguides.com\/it\/category\/tour-a-piedi\/\" \/>\n<meta property=\"og:site_name\" content=\"All sevilla Guides\" \/>\n<meta property=\"og:image\" content=\"https:\/\/allsevillaguides.com\/wp-content\/uploads\/2026\/04\/sevilla-tours-guiados.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1256\" \/>\n\t<meta property=\"og:image:height\" content=\"658\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AllSevillaTours\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/allsevillaguides.com\\\/it\\\/category\\\/tour-a-piedi\\\/\",\"url\":\"https:\\\/\\\/allsevillaguides.com\\\/it\\\/category\\\/tour-a-piedi\\\/\",\"name\":\"Tour a piedi archivos | All sevilla Guides\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/allsevillaguides.com\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/allsevillaguides.com\\\/it\\\/category\\\/tour-a-piedi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/allsevillaguides.com\\\/it\\\/category\\\/tour-a-piedi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/allsevillaguides.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tour a piedi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/allsevillaguides.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/allsevillaguides.com\\\/it\\\/\",\"name\":\"Allsevillaguides.com\",\"description\":\"Visitas guiadas y experiencias \u00fanicas en Sevilla, Espa\u00f1a\",\"publisher\":{\"@id\":\"https:\\\/\\\/allsevillaguides.com\\\/it\\\/#organization\"},\"alternateName\":\"All Sevilla Guides\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/allsevillaguides.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/allsevillaguides.com\\\/it\\\/#organization\",\"name\":\"All Sevilla Tours\",\"alternateName\":\"All Sevilla Guides\",\"url\":\"https:\\\/\\\/allsevillaguides.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/allsevillaguides.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/allsevillaguides.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/LOGO-PINK.svg\",\"contentUrl\":\"https:\\\/\\\/allsevillaguides.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/LOGO-PINK.svg\",\"caption\":\"All Sevilla Tours\"},\"image\":{\"@id\":\"https:\\\/\\\/allsevillaguides.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AllSevillaTours\\\/?ref=aymt_homepage_panel\",\"https:\\\/\\\/x.com\\\/AllSevillaTours\",\"https:\\\/\\\/www.instagram.com\\\/all.sevilla.tours\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCud-_NKc0HV8USIsOk5R1qw?disable_polymer=true\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tour a piedi archivos | All sevilla Guides","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/allsevillaguides.com\/it\/category\/tour-a-piedi\/","og_locale":"it_IT","og_type":"article","og_title":"Tour a piedi archivos | All sevilla Guides","og_url":"https:\/\/allsevillaguides.com\/it\/category\/tour-a-piedi\/","og_site_name":"All sevilla Guides","og_image":[{"width":1256,"height":658,"url":"https:\/\/allsevillaguides.com\/wp-content\/uploads\/2026\/04\/sevilla-tours-guiados.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@AllSevillaTours","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/allsevillaguides.com\/it\/category\/tour-a-piedi\/","url":"https:\/\/allsevillaguides.com\/it\/category\/tour-a-piedi\/","name":"Tour a piedi archivos | All sevilla Guides","isPartOf":{"@id":"https:\/\/allsevillaguides.com\/it\/#website"},"breadcrumb":{"@id":"https:\/\/allsevillaguides.com\/it\/category\/tour-a-piedi\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/allsevillaguides.com\/it\/category\/tour-a-piedi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/allsevillaguides.com\/it\/"},{"@type":"ListItem","position":2,"name":"Tour a piedi"}]},{"@type":"WebSite","@id":"https:\/\/allsevillaguides.com\/it\/#website","url":"https:\/\/allsevillaguides.com\/it\/","name":"Allsevillaguides.com","description":"Visitas guiadas y experiencias \u00fanicas en Sevilla, Espa\u00f1a","publisher":{"@id":"https:\/\/allsevillaguides.com\/it\/#organization"},"alternateName":"All Sevilla Guides","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/allsevillaguides.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/allsevillaguides.com\/it\/#organization","name":"All Sevilla Tours","alternateName":"All Sevilla Guides","url":"https:\/\/allsevillaguides.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/allsevillaguides.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/allsevillaguides.com\/wp-content\/uploads\/2025\/12\/LOGO-PINK.svg","contentUrl":"https:\/\/allsevillaguides.com\/wp-content\/uploads\/2025\/12\/LOGO-PINK.svg","caption":"All Sevilla Tours"},"image":{"@id":"https:\/\/allsevillaguides.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AllSevillaTours\/?ref=aymt_homepage_panel","https:\/\/x.com\/AllSevillaTours","https:\/\/www.instagram.com\/all.sevilla.tours\/","https:\/\/www.youtube.com\/channel\/UCud-_NKc0HV8USIsOk5R1qw?disable_polymer=true"]}]}},"_links":{"self":[{"href":"https:\/\/allsevillaguides.com\/it\/wp-json\/wp\/v2\/categories\/141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/allsevillaguides.com\/it\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/allsevillaguides.com\/it\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/allsevillaguides.com\/it\/wp-json\/wp\/v2\/posts?categories=141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}